{"id":109501,"date":"2022-10-25T15:41:00","date_gmt":"2022-10-25T15:41:00","guid":{"rendered":"https:\/\/pruefengel.de\/mardermaeuse-vertreiber-test"},"modified":"2025-04-30T12:20:23","modified_gmt":"2025-04-30T12:20:23","slug":"repulsif-martressouris-en-test-2022","status":"publish","type":"post","link":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/","title":{"rendered":"R\u00e9pulsif martres+souris en test 2022"},"content":{"rendered":"<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><p>Lors de notre test, le <strong>r\u00e9pulsif \u00e0 martres et souris <\/strong>d&rsquo;<strong>ISOTRONIC <\/strong>a fait tr\u00e8s bonne impression. <br>Outre son <strong>installation facile<\/strong> au moyen de colliers de serrage ou de vis, il s\u00e9duit par sa <strong>taille pratique<\/strong> et son <strong>utilisation mobile<\/strong>. Le produit offre une <strong>protection durable contre les martres<\/strong> gr\u00e2ce aux ondes ultrasoniques dans un <strong>rayon d&rsquo;action allant jusqu&rsquo;\u00e0 40 m\u00b2<\/strong>. Il n&rsquo;utilise pas d&rsquo;agents chimiques. En outre, la <strong>dur\u00e9e de vie des piles est d&rsquo;environ 8 mois<\/strong> et il est dot\u00e9 d&rsquo;un <strong>syst\u00e8me d&rsquo;arr\u00eat automatique <\/strong>pour l&rsquo;utilisation dans le compartiment moteur. N\u00e9anmoins, <strong>des informations plus explicites sur une \u00e9ventuelle r\u00e9sistance \u00e0 l&rsquo;eau<\/strong> auraient \u00e9t\u00e9 souhaitables.<\/p><div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-uagb-advanced-heading uagb-block-4b071702\"><h4 class=\"uagb-heading-text\"><strong>Avantages<\/strong><\/h4><\/div><p>\u2705 pas d&rsquo;agents chimiques<br>\u2705 installation facile<br>\u2705 entreprise familiale<br>\u2705 mat\u00e9riel de montage et piles inclus<\/p><\/div><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-uagb-advanced-heading uagb-block-0e28725e\"><h4 class=\"uagb-heading-text\"><strong>Inconv\u00e9nients<\/strong><\/h4><\/div><p>\u274c pas d&rsquo;information sur la r\u00e9sistance \u00e0 l&rsquo;eau<\/p><\/div><\/div><div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-uagb-advanced-heading uagb-block-de0dc7e9\"><\/div><div class=\"wp-block-uagb-advanced-heading uagb-block-b8dc512d\" id=\"der-erste-eindruck\"><h2 class=\"uagb-heading-text\">La premi\u00e8re impression<\/h2><p class=\"uagb-desc-text\">L&#8217;emballage et les marquages<\/p><\/div><div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><p style=\"font-size:14px\">\u2139\ufe0f Nous nous penchons ici plus en d\u00e9tail sur l&#8217;emballage. La durabilit\u00e9 est un facteur de plus en plus important. En outre, il faut bien s\u00fbr assurer une protection suffisante du produit.<\/p><figure class=\"wp-block-table is-style-regular\"><table class=\"has-white-background-color has-background\"><thead><tr><th>Crit\u00e8re<\/th><th>Remarque<\/th><th>Score obtenu*<\/th><\/tr><\/thead><tbody><tr><td>Protection des produits<\/td><td>Le carton est solide, le produit est suffisamment prot\u00e9g\u00e9<\/td><td>100 points<\/td><\/tr><tr><td>Durabilit\u00e9 Emballage<\/td><td>Pas de d\u00e9chets d&#8217;emballage inutiles, pas d&rsquo;utilisation de plastique.<\/td><td>95 points<\/td><\/tr><tr><td>Marquage des produits<\/td><td>\u00c9tiquetage pr\u00e9sent sur le produit et le carton<\/td><td>100 points<\/td><\/tr><tr><td>Autres<\/td><td>emballage de qualit\u00e9, convient \u00e9galement pour les cadeaux<\/td><td>100 points<\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td><strong>Total<\/strong><\/td><td><strong>99 points<\/strong><\/td><\/tr><\/tfoot><\/table><figcaption class=\"wp-element-caption\"><strong>Pond\u00e9ration : 15%.<\/strong><br>*Le score maximum est de 100 points <\/figcaption><\/figure><div class=\"wp-block-uagb-container uagb-block-6ba30961 alignwide uagb-is-root-container\"><div class=\"wp-block-uagb-container uagb-block-4ab2861b\"><div class=\"wp-block-uagb-image uagb-block-69d4aca3 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/media.pruefengel.de\/2022\/10\/WhatsApp-Image-2022-10-24-at-19.53.15.webp\" alt=\"Marder+M\u00e4use Vertreiber\" class=\"uag-image-5145\" width=\"\" height=\"\" title=\"\" \/><figcaption class=\"uagb-image-caption\">Chasseur de martres+souris<br>Emballage<\/figcaption><\/figure><\/div><\/div><p>Le <strong>r\u00e9pulsif pour martres et souris <\/strong>d&rsquo;<strong>ISOTRONIC <\/strong>est arriv\u00e9 pour notre test dans un carton d&rsquo;exp\u00e9dition typique. Celui-ci \u00e9tait <strong>intact <\/strong>et facile \u00e0 ouvrir en retirant la bande adh\u00e9sive. Le carton contenait le distributeur de martres et de souris emball\u00e9 dans du papier ainsi que ses accessoires. Gr\u00e2ce au mode d&#8217;emballage, le produit est prot\u00e9g\u00e9 de mani\u00e8re optimale contre les rayures et la salet\u00e9. La <strong>protection du produit<\/strong> a donc \u00e9t\u00e9 <strong>enti\u00e8rement garantie<\/strong> et le distributeur de martres+souris a \u00e9t\u00e9 livr\u00e9 dans un <strong>\u00e9tat irr\u00e9prochable<\/strong>. <br>De plus, l&#8217;emballage est enti\u00e8rement <strong>recyclable<\/strong>. Sur ce point, le produit laisse une <strong>tr\u00e8s bonne premi\u00e8re impression<\/strong>. Ni l&rsquo;appareil ni l&#8217;emballage utilis\u00e9 n&rsquo;\u00e9taient endommag\u00e9s.<\/p><\/div><div style=\"height:\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-uagb-advanced-heading uagb-block-b0cbc63b\"><h2 class=\"uagb-heading-text\">Apr\u00e8s le d\u00e9ballage<\/h2><p class=\"uagb-desc-text\">Contenu de l&#8217;emballage et instructions<\/p><\/div><div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><p style=\"font-size:14px\">\u2139\ufe0f La premi\u00e8re impression apr\u00e8s le d\u00e9ballage est celle que la plupart des gens gardent en m\u00e9moire. Le contenu de l&#8217;emballage est-il complet et le fabricant me facilite-t-il autant que possible l&rsquo;utilisation directe du produit ?<\/p><figure class=\"wp-block-table is-style-regular\"><table class=\"has-white-background-color has-background\"><thead><tr><th>Crit\u00e8re<\/th><th>Remarque<\/th><th>Score obtenu*<\/th><\/tr><\/thead><tbody><tr><td>Contenu de l&#8217;emballage &#038; \u00e9tendue<\/td><td>Chasseur de martres+souris, piles et mat\u00e9riel de montage inclus<\/td><td>100 points<\/td><\/tr><tr><td>Mode d&#8217;emploi<\/td><td>7 langues (dont l&rsquo;allemand), \u00e9crites de mani\u00e8re compr\u00e9hensible<\/td><td>100 points<\/td><\/tr><tr><td>Informations de contact<\/td><td>Se trouvent sur le carton, pas de hotline client disponible<\/td><td>90 points<\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td><strong>Total<\/strong><\/td><td><strong>97 points<\/strong><\/td><\/tr><\/tfoot><\/table><figcaption class=\"wp-element-caption\"><strong>Pond\u00e9ration : 15%.<\/strong><br>*Le score maximum est de 100 points <\/figcaption><\/figure><div class=\"wp-block-uagb-container uagb-block-4f74e821 alignwide uagb-is-root-container\"><div class=\"wp-block-uagb-container uagb-block-64aea7af\"><p>Apr\u00e8s le d\u00e9ballage, cinq \u00e9l\u00e9ments se sont retrouv\u00e9s sur la table. Outre le <strong>r\u00e9pulsif pour martres et souris <\/strong>, des <strong>piles, du mat\u00e9riel de montage<\/strong> et un petit <strong>tournevis <\/strong>ont \u00e9t\u00e9 livr\u00e9s. En outre, le <strong>mode d&#8217;emploi en sept langues<\/strong> et l&#8217;emballage d\u00e9crivent l&rsquo;utilisation correcte du produit. Les informations de contact se trouvent sur le carton du produit, l&rsquo;adresse e-mail ne s&rsquo;affichant qu&rsquo;en scannant un code QR. Il n&rsquo;y a cependant pas de hotline pour les clients.<br>N\u00e9anmoins, nous parlons d&rsquo;une <strong>tr\u00e8s bonne fa\u00e7on<\/strong> d&rsquo;envoyer un produit.<\/p><\/div><div class=\"wp-block-uagb-container uagb-block-93b9ec94\"><figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04a05c8407a&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"962\" height=\"962\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/media.pruefengel.de\/2022\/10\/WhatsApp-Image-2022-10-24-at-19.53.47.webp\" alt=\"Marder+M\u00e4use Vertreiber\" class=\"wp-image-5147\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">R\u00e9pulsif fouines+souris<br>Unboxing<\/figcaption><\/figure><\/div><\/div><div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-uagb-advanced-heading uagb-block-83098c3b\" id=\"das-erste-mal-in-der-hand\"\"><h2 class=\"uagb-heading-text\">La premi\u00e8re fois dans la main<\/h2><p class=\"uagb-desc-text\">Traitement et apparence des produits<\/p><\/div><p><\/p><p style=\"font-size:14px\">\u2139\ufe0f Avant de passer au test pratique, nous examinons de pr\u00e8s la finition du produit. Quelle est la qualit\u00e9 des mat\u00e9riaux utilis\u00e9s ? Le toucher et l&rsquo;aspect sont-ils satisfaisants ?<\/p><figure class=\"wp-block-table is-style-regular\"><table class=\"has-white-background-color has-background\"><thead><tr><th>Crit\u00e8re<\/th><th>Remarque<\/th><th>Score obtenu*<\/th><\/tr><\/thead><tbody><tr><td>Aspect visuel<\/td><td>Plastique, mais tr\u00e8s bon aspect visuel<\/td><td>100 points<\/td><\/tr><tr><td>Traitement <\/td><td>Tr\u00e8s bonne finition, aucune ar\u00eate, mais quelques petits d\u00e9fauts<\/td><td>90 points<\/td><\/tr><tr><td>Stabilit\u00e9<\/td><td>Tr\u00e8s stable<\/td><td>95 points<\/td><\/tr><tr><td>Durabilit\u00e9 du produit<\/td><td>Pas d&rsquo;information sur la durabilit\u00e9, mais l&#8217;emballage a \u00e9t\u00e9 con\u00e7u pour \u00e9viter les d\u00e9chets<\/td><td>75 points<\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td><strong>Total<\/strong><\/td><td><strong>90 points<\/strong><\/td><\/tr><\/tfoot><\/table><figcaption class=\"wp-element-caption\"><strong>Pond\u00e9ration : 20%.<\/strong><br>*Le score maximum est de 100 points<\/figcaption><\/figure><div class=\"wp-block-uagb-container uagb-block-e1db523c alignwide uagb-is-root-container\"><div class=\"wp-block-uagb-container uagb-block-4173b208\"><div class=\"wp-block-uagb-image uagb-block-e184d74c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/media.pruefengel.de\/2022\/10\/WhatsApp-Image-2022-10-24-at-19.54.32.webp\" alt=\"Marder+M\u00e4use Vertreiber\" class=\"uag-image-5148\" width=\"\" height=\"\" title=\"\" \/><figcaption class=\"uagb-image-caption\">Chasseur de martres+souris, piles et mat\u00e9riel de montage inclus<\/figcaption><\/figure><\/div><\/div><div class=\"wp-block-uagb-container uagb-block-17b8a048\"><p>Il faut d&rsquo;abord mentionner que le chasseur de martres et de souris donne une <strong>bonne<\/strong> <strong>impression visuelle<\/strong>. Il a des coins arrondis, mais <strong>des petits d\u00e9fauts de fabrication<\/strong>. Le bo\u00eetier du produit est en plastique, mais il tient tr\u00e8s bien dans la main. En outre, l&rsquo;appareil se distingue par son <strong>faible poids<\/strong> et sa <strong>finition solide<\/strong>. De plus, le distributeur de souris et de martres ne se plie pas et reste rigide.<br>On ne trouve des indications sur la durabilit\u00e9 que pour le mode d&#8217;emballage, mais le produit lui-m\u00eame n&rsquo;utilise <strong>pas d&rsquo;agents chimiques<\/strong>. De plus, la recherche et le d\u00e9veloppement ont \u00e9t\u00e9 effectu\u00e9s en Allemagne. De plus, le fabricant accorde une <strong>garantie de deux ans<\/strong>.<\/p><\/div><\/div><div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-uagb-advanced-heading uagb-block-e77326ff\" id=\"das-hat-unser-praxistest-ergeben\"><h2 class=\"uagb-heading-text\">Voici ce qu&rsquo;a r\u00e9v\u00e9l\u00e9 notre test pratique<\/h2><p class=\"uagb-desc-text\">Le fabricant tient-il ses promesses publicitaires ?<\/p><\/div><div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><p style=\"font-size:14px\">\u2139\ufe0f Notre test pratique est le plus important et a donc le plus de poids. Ici, le produit doit se soumettre \u00e0 diff\u00e9rents crit\u00e8res et tests. Nous v\u00e9rifions les fonctions et les promesses de l&rsquo;article test\u00e9. <\/p><figure class=\"wp-block-table is-style-regular\"><table class=\"has-white-background-color has-background\"><thead><tr><th>Crit\u00e8re<\/th><th>Remarque<\/th><th>Score obtenu*<\/th><\/tr><\/thead><tbody><tr><td>Fixation<\/td><td>Visser ou attacher le c\u00e2ble<\/td><td>90 points<\/td><\/tr><tr><td>Structure<\/td><td>Petit tournevis<\/td><td>85 points<\/td><\/tr><tr><td>Bruits<\/td><td>Non perceptible<\/td><td>90 points<\/td><\/tr><tr><td>Aptitude<\/td><td>Aucune information sur la r\u00e9sistance \u00e0 l&rsquo;eau<\/td><td>70 points<\/td><\/tr><tr><td>T\u00e9moin lumineux<\/td><td>Fonctionne parfaitement, clic silencieux<\/td><td>90 points<\/td><\/tr><tr><td>Efficacit\u00e9 et dur\u00e9e de vie des piles<\/td><td>Non \u00e9valuable pendant la p\u00e9riode de test<\/td><td> <\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td><strong>Total<\/strong><\/td><td><strong>85 points<\/strong><\/td><\/tr><\/tfoot><\/table><figcaption class=\"wp-element-caption\"><strong>Pond\u00e9ration : 30%.<\/strong><br>*Le score maximum est de 100 points<\/figcaption><\/figure><div class=\"wp-block-uagb-container uagb-block-9fa696f9 alignwide uagb-is-root-container\"><div class=\"wp-block-uagb-container uagb-block-11c90a59\"><p>Pour pouvoir utiliser le chasseur de martres et de souris, il faut d&rsquo;abord installer les piles fournies (6 x AAA). L&rsquo;ouverture du bo\u00eetier s&rsquo;av\u00e8re un peu <strong>plus difficile<\/strong> au d\u00e9but, car le tournevis fourni se comporte de mani\u00e8re inhabituelle et le couvercle ne peut \u00eatre retir\u00e9 qu&rsquo;avec d&rsquo;autres outils. Ensuite, l&rsquo;appareil peut \u00eatre install\u00e9 par exemple dans <strong>le compartiment moteur, la grange, le grenier ou le garage <\/strong>\u00e0 l&rsquo;aide des <strong>colliers de serrage <\/strong>ou des <strong>vis <\/strong>fournis. Les chevilles ne sont pas incluses, mais ne sont pas n\u00e9cessaires en raison du poids.<br>En raison de l&rsquo;\u00e9mission courte et intermittente de sons \u00e0 haute fr\u00e9quence, le fabricant promet une <strong>dur\u00e9e de vie des piles d&rsquo;environ huit mois<\/strong>. Dans le cas d&rsquo;une installation dans le compartiment moteur, l&rsquo;appareil n&rsquo;\u00e9met son son \u00e0 haute fr\u00e9quence que lorsque le v\u00e9hicule est \u00e0 l&rsquo;arr\u00eat. Sinon, l&rsquo;appareil retentit en permanence avec ses 23 kHz dans l&rsquo;intervalle mentionn\u00e9. La fr\u00e9quence n&rsquo;\u00e9tait <strong>pas perceptible<\/strong> pour nous lors du test, mais le bon fonctionnement a pu \u00eatre confirm\u00e9 par le <strong>t\u00e9moin lumineux rouge<\/strong>. Son clignotement \u00e9met un <strong>l\u00e9ger clic<\/strong>, ce qui ne devrait toutefois pas g\u00eaner lors d&rsquo;une installation dans les lieux mentionn\u00e9s. Un test \u00e0 long terme devrait permettre de d\u00e9terminer l&rsquo;effet du produit dans la pratique. Malheureusement, le fabricant ne donne pas d&rsquo;informations explicites sur une \u00e9ventuelle <strong>r\u00e9sistance \u00e0 l&rsquo;eau<\/strong>, de sorte qu&rsquo;il n&rsquo;est <strong>pas<\/strong> possible de <strong>garantir<\/strong> une utilisation appropri\u00e9e dans certains endroits en plein air. Seul le <strong>d\u00e9montage avant un lavage du moteur<\/strong> a \u00e9t\u00e9 indiqu\u00e9 en cas d&rsquo;utilisation dans le compartiment moteur.<\/p><\/div><div class=\"wp-block-uagb-container uagb-block-8057e132\"><figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04a05c85d8b&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/media.pruefengel.de\/2022\/10\/WhatsApp-Image-2022-10-26-at-09.47.45.webp\" alt=\"Marder+M\u00e4use Vertreiber\" class=\"wp-image-5238\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Chasseur de fouines et de souris<br>installation rapide<\/figcaption><\/figure><\/div><\/div><div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-uagb-advanced-heading uagb-block-c55bf695\" id=\"preis-leistungsverhaltnis\"><h2 class=\"uagb-heading-text\">Rapport qualit\u00e9\/prix<\/h2><p class=\"uagb-desc-text\">et les \u00e9valuations des consommateurs<\/p><\/div><div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><p style=\"font-size:14px\">\u2139\ufe0f Enfin, nous nous penchons sur la mani\u00e8re dont le produit se compare \u00e0 la concurrence. Peut-il rivaliser avec la concurrence en termes de prix et de qualit\u00e9 ? Recommanderions-nous g\u00e9n\u00e9ralement son achat ? Nous examinons \u00e9galement les \u00e9valuations des consommateurs et v\u00e9rifions si les critiques et les avis positifs sont r\u00e9ellement justifi\u00e9s.<\/p><figure class=\"wp-block-table is-style-regular\"><table class=\"has-white-background-color has-background\"><thead><tr><th>Crit\u00e8re<\/th><th>Remarque<\/th><th>Score obtenu*<\/th><\/tr><\/thead><tbody><tr><td>Rapport qualit\u00e9\/prix<\/td><td>Tr\u00e8s bon<\/td><td>95 points<\/td><\/tr><tr><td>Coupe d&rsquo;\u00e9valuation<\/td><td>3,9 sur 5,0 sur Amazon<\/td><td>45 points<\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td><strong>Total<\/strong><\/td><td><strong>70 points<\/strong><\/td><\/tr><\/tfoot><\/table><figcaption class=\"wp-element-caption\"><strong>Pond\u00e9ration : 20%.<\/strong><br>*Le score maximum est de 100 points<\/figcaption><\/figure><p>Sur la plateforme <strong><a href=\"https:\/\/www.amazon.de\/ISOTRONIC-Marderscheuche-Marderabwehr-M%C3%A4useschreck-Marderschutz\/dp\/B0765CC86P\/ref=sr_1_7?__mk_de_DE=%C3%85M%C3%85%C5%BD%C3%95%C3%91&#038;crid=1NDWE2ZDEWIXS&#038;keywords=isotronic+mardervertreiber&#038;qid=1666633605&#038;sprefix=isotronic+mardervertreiber%2Caps%2C91&#038;sr=8-7\">Amazon<\/a><\/strong>, les consommateurs ont attribu\u00e9 au produit une note moyenne de <strong>3,9 \u00e9toiles<\/strong>. Certains regrettent que le produit <strong>n&rsquo;ait aucun effet<\/strong> sur les fouines. En revanche, d&rsquo;autres personnes ont pu confirmer l&rsquo;<strong>effet positif<\/strong>. Les avis divergent \u00e9galement sur la <strong>dur\u00e9e de vie de la batterie<\/strong>. En revanche, de nombreux clients appr\u00e9cient la <strong>construction compacte et la facilit\u00e9 de montage<\/strong>. Lors de notre test pratique, nous avons pu confirmer que l&rsquo;<strong>installation<\/strong> se fait <strong>sans effort<\/strong> et que l&rsquo;appareil pr\u00e9sente un <strong>design pratique<\/strong>. Nous ne pouvons pas faire de d\u00e9claration g\u00e9n\u00e9rale sur l&rsquo;utilit\u00e9 r\u00e9elle, car il faudrait pour cela un test pratique sur une longue p\u00e9riode. En outre, nous estimons qu&rsquo;il serait judicieux de fournir des informations explicites sur une \u00e9ventuelle r\u00e9sistance \u00e0 l&rsquo;eau.<\/p><p>Pour des produits \u00e9quivalents, les prix sur Internet peuvent aller jusqu&rsquo;\u00e0 <strong>138 \u20ac<\/strong>. En revanche, des produits tr\u00e8s bon march\u00e9 sont disponibles <strong>\u00e0 partir de 7 \u20ac<\/strong>. Ainsi, avec un prix actuel de <strong>34,95 \u20ac<\/strong>, le <strong>distributeur de martres et de souris ISOTRONIC<\/strong> se situe dans le segment de prix inf\u00e9rieur. Par cons\u00e9quent, le <strong>rapport qualit\u00e9\/prix <\/strong>est <strong>tr\u00e8s bon<\/strong>.<\/p><div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-uagb-advanced-heading uagb-block-075d312f\" id=\"gesamtergebnis\"><h2 class=\"uagb-heading-text\">R\u00e9sultat global<\/h2><\/div><figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th><\/th><th class=\"has-text-align-center\" data-align=\"center\">Pond\u00e9ration<\/th><th class=\"has-text-align-center\" data-align=\"center\">Score obtenu*<\/th><\/tr><\/thead><tbody><tr><td>1. emballage &#038; \u00e9tiquetage<\/td><td class=\"has-text-align-center\" data-align=\"center\">15%<\/td><td class=\"has-text-align-center\" data-align=\"center\">99 points<\/td><\/tr><tr><td>2. contenu de l&#8217;emballage &#038; instructions <\/td><td class=\"has-text-align-center\" data-align=\"center\">15%<\/td><td class=\"has-text-align-center\" data-align=\"center\">97 points<\/td><\/tr><tr><td>3. traitement du produit &#038; apparence<\/td><td class=\"has-text-align-center\" data-align=\"center\">20%<\/td><td class=\"has-text-align-center\" data-align=\"center\">90 points<\/td><\/tr><tr><td>4. en test pratique<\/td><td class=\"has-text-align-center\" data-align=\"center\">30%<\/td><td class=\"has-text-align-center\" data-align=\"center\">85 points<\/td><\/tr><tr><td>5. prix\/performance &#038; avis des consommateurs<\/td><td class=\"has-text-align-center\" data-align=\"center\">20%<\/td><td class=\"has-text-align-center\" data-align=\"center\">70 points<\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Total<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>85 points<\/strong><\/td><\/tr><\/tfoot><\/table><figcaption class=\"wp-element-caption\">*Le score maximum est de 100 points<\/figcaption><\/figure><div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-uagb-container uagb-block-9abbd174 alignwide uagb-is-root-container\"><div class=\"wp-block-uagb-container uagb-block-ea653987\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Lors de notre test, le r\u00e9pulsif \u00e0 martres et souris d&rsquo;ISOTRONIC a fait tr\u00e8s bonne impression. Outre son installation facile au moyen de colliers de serrage ou de vis, il s\u00e9duit par sa taille pratique et son utilisation mobile. Le produit offre une protection durable contre les martres gr\u00e2ce aux ondes ultrasoniques dans un rayon [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":5144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_gspb_post_css":"","inline_featured_image":false,"_uag_custom_page_level_css":"","ub_ctt_via":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[6234,6224,6217,6233],"tags":[6728,6766,6510,6767,6768,6769,6511,6512],"table_tags":[],"class_list":["post-109501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outdoor","category-garten","category-technik","category-auto-und-motorrad","tag-auto-fr","tag-garage-fr","tag-marder-fr","tag-marderfrei-fr","tag-mausfrei-fr","tag-schutz-fr","tag-ultraschall-fr","tag-vertreiben-fr"],"acf":[],"featured_image_src":"https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp","author_info":{"display_name":"Agnes Kuehne","author_link":"https:\/\/pruefengel.de\/fr\/author\/agnes-kuehne\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9pulsif martres+souris en test 2022 - Pr\u00fcfengel<\/title>\n<meta name=\"description\" content=\"Um dem Endverbraucher eine sichere Kaufentscheidung zu erm\u00f6glichen, zertifiziert und vergleicht das Pr\u00fcfengel Institut Produkte und Dienstleistungen. Hier wurden der Marder+M\u00e4use Vertreiber von ISOTRONIC getestet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9pulsif martres+souris en test 2022 - Pr\u00fcfengel\" \/>\n<meta property=\"og:description\" content=\"Um dem Endverbraucher eine sichere Kaufentscheidung zu erm\u00f6glichen, zertifiziert und vergleicht das Pr\u00fcfengel Institut Produkte und Dienstleistungen. Hier wurden der Marder+M\u00e4use Vertreiber von ISOTRONIC getestet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00fcfengel\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T15:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T12:20:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pruefengel.de\/wp-content\/uploads\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Agnes Kuehne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agnes Kuehne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/\"},\"author\":{\"name\":\"Agnes Kuehne\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#\\\/schema\\\/person\\\/2dbf9c980463c50d460d1d444959202f\"},\"headline\":\"R\u00e9pulsif martres+souris en test 2022\",\"datePublished\":\"2022-10-25T15:41:00+00:00\",\"dateModified\":\"2025-04-30T12:20:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/\"},\"wordCount\":578,\"publisher\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.pruefengel.de\\\/2044\\\/10\\\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp\",\"keywords\":[\"Auto\",\"Garage\",\"Marder\",\"Marderfrei\",\"mausfrei\",\"Schutz\",\"ultraschall\",\"vertreiben\"],\"articleSection\":[\"Ext\u00e9rieur\",\"Jardin\",\"Technique\",\"Voiture &amp; Moto\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/\",\"url\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/\",\"name\":\"R\u00e9pulsif martres+souris en test 2022 - Pr\u00fcfengel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.pruefengel.de\\\/2044\\\/10\\\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp\",\"datePublished\":\"2022-10-25T15:41:00+00:00\",\"dateModified\":\"2025-04-30T12:20:23+00:00\",\"description\":\"Um dem Endverbraucher eine sichere Kaufentscheidung zu erm\u00f6glichen, zertifiziert und vergleicht das Pr\u00fcfengel Institut Produkte und Dienstleistungen. Hier wurden der Marder+M\u00e4use Vertreiber von ISOTRONIC getestet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.pruefengel.de\\\/2044\\\/10\\\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp\",\"contentUrl\":\"https:\\\/\\\/media.pruefengel.de\\\/2044\\\/10\\\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp\",\"width\":550,\"height\":550,\"caption\":\"Marderschutz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/repulsif-martressouris-en-test-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9pulsif martres+souris en test 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/\",\"name\":\"Pr\u00fcfengel\",\"description\":\"Wir testen Produkte!\",\"publisher\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#organization\",\"name\":\"Pr\u00fcfengel Institut\",\"url\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/pruefengel.de\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Icon.png\",\"contentUrl\":\"http:\\\/\\\/pruefengel.de\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Icon.png\",\"width\":2000,\"height\":1539,\"caption\":\"Pr\u00fcfengel Institut\"},\"image\":{\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pruefengel.de\\\/fr\\\/#\\\/schema\\\/person\\\/2dbf9c980463c50d460d1d444959202f\",\"name\":\"Agnes Kuehne\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954fe413a033e3947eb09f28ac16fd0257d9b9995a23cc89357096e77d958575?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954fe413a033e3947eb09f28ac16fd0257d9b9995a23cc89357096e77d958575?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954fe413a033e3947eb09f28ac16fd0257d9b9995a23cc89357096e77d958575?s=96&d=mm&r=g\",\"caption\":\"Agnes Kuehne\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9pulsif martres+souris en test 2022 - Pr\u00fcfengel","description":"Um dem Endverbraucher eine sichere Kaufentscheidung zu erm\u00f6glichen, zertifiziert und vergleicht das Pr\u00fcfengel Institut Produkte und Dienstleistungen. Hier wurden der Marder+M\u00e4use Vertreiber von ISOTRONIC getestet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9pulsif martres+souris en test 2022 - Pr\u00fcfengel","og_description":"Um dem Endverbraucher eine sichere Kaufentscheidung zu erm\u00f6glichen, zertifiziert und vergleicht das Pr\u00fcfengel Institut Produkte und Dienstleistungen. Hier wurden der Marder+M\u00e4use Vertreiber von ISOTRONIC getestet.","og_url":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/","og_site_name":"Pr\u00fcfengel","article_published_time":"2022-10-25T15:41:00+00:00","article_modified_time":"2025-04-30T12:20:23+00:00","og_image":[{"width":550,"height":550,"url":"https:\/\/pruefengel.de\/wp-content\/uploads\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp","type":"image\/webp"}],"author":"Agnes Kuehne","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Agnes Kuehne","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/#article","isPartOf":{"@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/"},"author":{"name":"Agnes Kuehne","@id":"https:\/\/pruefengel.de\/fr\/#\/schema\/person\/2dbf9c980463c50d460d1d444959202f"},"headline":"R\u00e9pulsif martres+souris en test 2022","datePublished":"2022-10-25T15:41:00+00:00","dateModified":"2025-04-30T12:20:23+00:00","mainEntityOfPage":{"@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/"},"wordCount":578,"publisher":{"@id":"https:\/\/pruefengel.de\/fr\/#organization"},"image":{"@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp","keywords":["Auto","Garage","Marder","Marderfrei","mausfrei","Schutz","ultraschall","vertreiben"],"articleSection":["Ext\u00e9rieur","Jardin","Technique","Voiture &amp; Moto"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/","url":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/","name":"R\u00e9pulsif martres+souris en test 2022 - Pr\u00fcfengel","isPartOf":{"@id":"https:\/\/pruefengel.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/#primaryimage"},"image":{"@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp","datePublished":"2022-10-25T15:41:00+00:00","dateModified":"2025-04-30T12:20:23+00:00","description":"Um dem Endverbraucher eine sichere Kaufentscheidung zu erm\u00f6glichen, zertifiziert und vergleicht das Pr\u00fcfengel Institut Produkte und Dienstleistungen. Hier wurden der Marder+M\u00e4use Vertreiber von ISOTRONIC getestet.","breadcrumb":{"@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/#primaryimage","url":"https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp","contentUrl":"https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp","width":550,"height":550,"caption":"Marderschutz"},{"@type":"BreadcrumbList","@id":"https:\/\/pruefengel.de\/fr\/repulsif-martressouris-en-test-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/pruefengel.de\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9pulsif martres+souris en test 2022"}]},{"@type":"WebSite","@id":"https:\/\/pruefengel.de\/fr\/#website","url":"https:\/\/pruefengel.de\/fr\/","name":"Pr\u00fcfengel","description":"Wir testen Produkte!","publisher":{"@id":"https:\/\/pruefengel.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pruefengel.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/pruefengel.de\/fr\/#organization","name":"Pr\u00fcfengel Institut","url":"https:\/\/pruefengel.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pruefengel.de\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/pruefengel.de\/wp-content\/uploads\/2022\/05\/Icon.png","contentUrl":"http:\/\/pruefengel.de\/wp-content\/uploads\/2022\/05\/Icon.png","width":2000,"height":1539,"caption":"Pr\u00fcfengel Institut"},"image":{"@id":"https:\/\/pruefengel.de\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pruefengel.de\/fr\/#\/schema\/person\/2dbf9c980463c50d460d1d444959202f","name":"Agnes Kuehne","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/954fe413a033e3947eb09f28ac16fd0257d9b9995a23cc89357096e77d958575?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/954fe413a033e3947eb09f28ac16fd0257d9b9995a23cc89357096e77d958575?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/954fe413a033e3947eb09f28ac16fd0257d9b9995a23cc89357096e77d958575?s=96&d=mm&r=g","caption":"Agnes Kuehne"}}]}},"uagb_featured_image_src":{"full":["https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp",550,550,false],"thumbnail":["https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2-150x150.webp",150,150,true],"medium":["https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2-300x300.webp",300,300,true],"medium_large":["https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp",550,550,false],"large":["https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp",550,550,false],"1536x1536":["https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp",550,550,false],"2048x2048":["https:\/\/media.pruefengel.de\/2044\/10\/b1a444_ad11ec89e3ee4c09b39d4878ebbc65b0mv2.webp",550,550,false]},"uagb_author_info":{"display_name":"Agnes Kuehne","author_link":"https:\/\/pruefengel.de\/fr\/author\/agnes-kuehne\/"},"uagb_comment_info":0,"uagb_excerpt":"Lors de notre test, le r\u00e9pulsif \u00e0 martres et souris d&rsquo;ISOTRONIC a fait tr\u00e8s bonne impression. Outre son installation facile au moyen de colliers de serrage ou de vis, il s\u00e9duit par sa taille pratique et son utilisation mobile. Le produit offre une protection durable contre les martres gr\u00e2ce aux ondes ultrasoniques dans un rayon\u2026","_links":{"self":[{"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/posts\/109501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/comments?post=109501"}],"version-history":[{"count":3,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/posts\/109501\/revisions"}],"predecessor-version":[{"id":142890,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/posts\/109501\/revisions\/142890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/media\/5144"}],"wp:attachment":[{"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/media?parent=109501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/categories?post=109501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/tags?post=109501"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/pruefengel.de\/fr\/wp-json\/wp\/v2\/table_tags?post=109501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}